{"id":40335,"date":"2024-10-14T08:30:20","date_gmt":"2024-10-14T06:30:20","guid":{"rendered":"https:\/\/marineforum.online\/?p=40335"},"modified":"2025-09-29T21:04:16","modified_gmt":"2025-09-29T19:04:16","slug":"late-and-too-expensive","status":"publish","type":"post","link":"https:\/\/marineforum.online\/en\/verspaetet-und-zu-teuer\/","title":{"rendered":"Delayed and too expensive"},"content":{"rendered":"<p><strong>Die Schiffsbeschaffung der US Navy liegt um mehrere Jahre hinter dem Zeitplan. Gleichzeitig explodieren die Kosten. Die Regierung k\u00fcndigt gezielte Ma\u00dfnahmen an.<\/strong><\/p>\n<p>Dass die meisten Schiffbauprojekte der US-Seestreitkr\u00e4fte hinter dem Zeitplan stehen, ist l\u00e4ngst bekannt. Die Hochseeflotte der Navy verf\u00fcgt gegenw\u00e4rtig \u00fcber weniger als 300 Einheiten einschlie\u00dflich der Flottenversorger. Das Pentagon sch\u00e4tzt, dass 381 Einheiten n\u00f6tig w\u00e4ren, um alle globalen Verpflichtungen der Marine wahrzunehmen. Das verz\u00f6gerte Schiffbautempo behindert den Flottenausbau und die Abl\u00f6sung \u00e4lterer Schiffe durch neue und leistungsstarke Einheiten. Dieser Umstand ist <div class='digimember_salesletter'><style>.hide-when-paywall{display:none!important;}<\/style>\n<div class=\"digimember_login_info_pop\">\n<div class=\"titel-top\">Zugang marineforum <span class=\"mfo-orange\">digital+<\/span><\/div>\n<div class=\"container-left-login\">\n<div class=\"titel-column\">Sie sind bereits registrierter Nutzer?<\/div>\n<div style=\"font-size: 20px; font-weight: bold;\">Jetzt hier einloggen - auch MOV Mitglieder:<\/div>\n<style type=\"text\/css\">\nform#login_2_form div.ncore_with_focus input[type=\"text\"],\nform#login_2_form div.ncore_with_focus input[type=\"password\"]\n{\n    border-color: #21759b;\n    \n}\n\nform#login_2_form div.ncore_with_focus label,\nform#login_2_form div.ncore_with_focus label\n{\n    color: #21759b;\n    \n}\n\n.button.button-primary.ncore_custom_button,\nform#login_2_form .button.button-primary {\n     background-color: #21759b;\n     color: #FFFFFF;\n     \n }\n<\/style><div class=\"ncore ncore_user_form_container digimember_login dm_signin_form_container ncore_with_wp_login ncore_without_fp_login\">\n    <div id='login_2_form_error_message' class='user_login_form_form_error_message'><\/div>    <form action=\"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335\" method=\"post\" id=\"login_2_form\" name=\"login_2_form\" class=\"ncore_user_form dm_signin_form ncore_form_narrow \">\n        <a name='login'><\/a><div class='ncore ncore_user_form'>\n<div class=\"ncore_hidden\"><input type='hidden' name='ncore_xss_password' value='YpVRUpVtOQstVs1o8n8SXn6WBCTm6L' \/><\/div><div class='ncore_form_row  ncore_input_text ncore_without_value'>\n    <div class='ncore_form_label  '>\n        <label for='ncore_username0'>Username<\/label>\n    <\/div>\n    <div class='ncore_form_input  '>\n         <input   id=\"ncore_username0\"   type=\"text\"    name=\"ncore_username0\"   \/>\n        \n    <\/div>\n<\/div>\n<div class='ncore_form_row  ncore_input_password ncore_without_value'>\n    <div class='ncore_form_label  '>\n        <label for='ncore_password0'>Password<\/label>\n    <\/div>\n    <div class='ncore_form_input  '>\n         <input   id=\"ncore_password0\"   type=\"password\"    name=\"ncore_password0\"   \/>\n        \n    <\/div>\n<\/div>\n<div class='ncore_form_row  ncore_input_checkbox ncore_without_value'>\n    <div class='ncore_form_input  '>\n         <label  ><span class='ncore_checkbox'><input type='checkbox'   id=\"ncore_remember0\"   name=\"checkbox_ncore_remember0\"   class=\"ncore_checkbox\"   data-value-checked=\"1\"   data-value-unchecked=\"0\"    \/> <input type='hidden' name='ncore_remember0' value='0'   class=\"vis_sel_remember_5400213659\"   \/><\/span> Remember me<\/label><div class='ncore_user_form footnote ncore_new_password_link'><a onclick=\"return ncore_new_password_link_5400213657();\" class='ncore_forgotton_password_link' href=\"\/\">Lost your password?<\/a><\/div>\n        \n    <\/div>\n<\/div>\n<\/div>\n<input   type=\"hidden\"   value=\"1\"   name=\"ncore_ncore_is_posted_00\"   \/><div class='ncore ncore_user ncore_form_buttons'><input   type='submit' onclick=\" var form = ncoreJQ( this ).closest( 'form' ); var container = form.parent(); var error_div =  container.find( '.user_login_form_form_error_message' ); var error_div_id = error_div.attr( 'id' ); var username = encodeURIComponent( form.find( 'input[name=ncore_username0]').val() ); var password = encodeURIComponent( form.find( 'input[name=ncore_password0]').val() ); var remember = form.find( 'input[name=ncore_remember0]').val() ? '1' : '0'; var data = { 'username': username, 'password': password, 'remember': remember, 'errordiv': error_div_id }; data.redirect_url='https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335'; data.current_url='https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335'; data.action='ncore_ajax_action'; data.ncore_plugin='digimember'; data.ncore_controller='user\/login_form'; data.ncore_event='login'; data.ncore_xss_password='YpVRUpVtOQstVs1o8n8SXn6WBCTm6L'; data.ncore_ctr_settings_0='stay_on_same_page'; data.ncore_ctr_settings_container_css='digimember_login dm_signin_form_container'; data.ncore_ctr_settings_form_css='dm_signin_form'; dmDialogAjax_Start(); ncoreJQ.post(ncore_ajax_url, data, dmDialogAjax_Callback ) .fail(function(result){ var callbackResult = { error: 'Action failed.', success: '', html: '', target_div_id: '', js: '', redirect: false, must_reload: false, }; if (result.status == 403 && result.responseText != '') { callbackResult.error = result.responseText; } dmDialogAjax_Callback(JSON.stringify(callbackResult)); });; return false;\" name='save' class='button button-primary ' value=\"Log In\" \/><\/div>    <\/form>\n\n<\/div>\n<br clear=\"all\" \/><\/p>\n<\/div>\n<div class=\"container-right-abo\">\n<div class=\"titel-column\">Sie haben noch keinen<br \/>\nZugang?<\/div>\n<div style=\"font-size: 20px; font-weight: bold;\">Hier geht es zum marineforum<span style=\"color: #ff6600;\"> digital+<\/span> Abo:<\/div>\n<ul>\n<li>Zugang zu allen Beitr\u00e4gen aus dem marineforum Magazin<\/li>\n<li>Einfache Zahlung per PayPal, Lastschriftverfahren oder Kreditkarte<\/li>\n<li>Das Abonnement ist jederzeit kostenfrei k\u00fcndbar<\/li>\n<li>F\u00fcr MOV-Mitglieder kostenfrei<\/li>\n<\/ul>\n<p><a class=\"abo-optionen\" href=\"https:\/\/marineforum.online\/infoseiten\/marineforum-magazin\/#online-abo\"><button class=\"mfo-button\">Zu den Abo-Optionen<\/button><\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Schiffsbeschaffung der US Navy liegt um mehrere Jahre hinter dem Zeitplan. Gleichzeitig explodieren die Kosten. Die Regierung k\u00fcndigt gezielte Ma\u00dfnahmen an. Dass die meisten Schiffbauprojekte der US-Seestreitkr\u00e4fte hinter dem Zeitplan stehen, ist l\u00e4ngst bekannt. Die Hochseeflotte der Navy verf\u00fcgt gegenw\u00e4rtig \u00fcber weniger als 300 Einheiten einschlie\u00dflich der Flottenversorger. Das Pentagon sch\u00e4tzt, dass 381 Einheiten [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":40337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"categories":[21,486,32],"tags":[8151,237,8154,8153,8152,1147,8150,394],"class_list":["post-40335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technologie","category-headlines","category-magazin","tag-kostenexplosion-schiffbau","tag-maritime-sicherheit","tag-militaertechnik","tag-pentagon-schiffsprojekte","tag-regierungsmassnahmen","tag-schiffbau","tag-schiffsbeschaffung-us-navy","tag-us-navy"],"acf":[],"_links":{"self":[{"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/comments?post=40335"}],"version-history":[{"count":1,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335\/revisions"}],"predecessor-version":[{"id":49473,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/posts\/40335\/revisions\/49473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/media\/40337"}],"wp:attachment":[{"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/media?parent=40335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/categories?post=40335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marineforum.online\/en\/wp-json\/wp\/v2\/tags?post=40335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}